{"id":947,"date":"2025-08-01T21:48:12","date_gmt":"2025-08-02T02:48:12","guid":{"rendered":"https:\/\/sinelliatea.com\/preparando-el-te-al-estilo-del-abuelo\/"},"modified":"2025-08-22T11:20:56","modified_gmt":"2025-08-22T16:20:56","slug":"preparando-el-te-al-estilo-del-abuelo","status":"publish","type":"post","link":"https:\/\/sinelliatea.com\/es\/preparando-el-te-al-estilo-del-abuelo\/","title":{"rendered":"Preparando el t\u00e9 al &#8216;estilo del abuelo&#8217;"},"content":{"rendered":"&#13;\n<p class=\"wp-block-paragraph\">Si alguna vez has visitado China o has vivido aqu\u00ed, habr\u00e1s notado que mucha gente, especialmente los residentes mayores, disfruta bebiendo el t\u00e9 en una taza o termo, dej\u00e1ndolo reposar todo el d\u00eda y, ocasionalmente, a\u00f1adi\u00e9ndole agua hirviendo. Taxistas, mec\u00e1nicos y peque\u00f1os comerciantes comparten esta pasi\u00f3n por lo que en Occidente se conoce como la preparaci\u00f3n del t\u00e9 al estilo del abuelo. <\/p>&#13;\n<p>Pero \u00bfpor qu\u00e9 se le llama \u00abPreparaci\u00f3n al estilo del abuelo\u00bb?<\/p>&#13;\n<p>Este t\u00e9rmino se debe a un famoso bloguero especializado en t\u00e9, \u00abMarshal\u00bb, una referencia entre los verdaderos amantes del t\u00e9, a quien tuvimos el placer de conocer en 2019 en Hong Kong, donde hablamos sobre la investigaci\u00f3n, los sutras y el estudio del t\u00e9 mientras beb\u00edamos t\u00e9 Pu&#8217;er a\u00f1ejado y almacenado en Hong Kong. Aqu\u00ed un extracto de su blog: <\/p>&#13;\n<p><em>\u201cEn resumen, el estilo abuelo significa preparar el t\u00e9 en una taza grande, sin filtros, bolitas de t\u00e9, bolsitas ni ning\u00fan otro elemento, rellenando constantemente con agua sin tener en cuenta el tiempo ni la temperatura de infusi\u00f3n. Los \u00fanicos tres elementos necesarios para la preparaci\u00f3n al estilo abuelo son hojas de t\u00e9, agua y una taza, preferiblemente grande. Lo llam\u00e9 estilo abuelo porque as\u00ed es como mi abuelo toma el t\u00e9 y es uno de los primeros recuerdos que tengo de gente tomando t\u00e9\u201d.<\/em><\/p>&#13;\n<p>Este m\u00e9todo suele provocar que el t\u00e9 quede demasiado infusionado (lo que los chinos llaman \u00absabor a sopa cocida\u00bb \u719f\u6c64\u5473), por lo que no suele ser el favorito de los profesionales del t\u00e9 chinos. Sin embargo, la preparaci\u00f3n al estilo abuelo puede resultar bastante sencilla si se siguen algunos consejos b\u00e1sicos.<\/p>&#13;\n<p>En esta publicaci\u00f3n, nos centraremos en el uso de un termo o una botella de t\u00e9 en lugar de un vaso alto o con tapa, pero el concepto es bastante similar.<\/p>&#13;\n<p><strong>Elige el termo adecuado: <\/strong>Recomendamos usar un termo de vidrio de borosilicato, que parece retener mejor el calor. Tambi\u00e9n preferimos los de metal en lugar de pl\u00e1stico. Aseg\u00farate de que sellen bien. Los mejores son los que tienen un bot\u00f3n de vertido que no requiere abrir la tapa, ya que se corre el riesgo de perder aromas y calor.   <strong> <\/strong><\/p>&#13;\n<p><strong>Prepara la cantidad adecuada de hojas de t\u00e9:<\/strong> Lo m\u00e1s f\u00e1cil es usar un tercio de lo que usar\u00edas en una gaiwan con el triple de agua. Pero la cantidad exacta depende completamente del t\u00e9, as\u00ed que pregunta a tu proveedor o, como siempre decimos: prueba una y otra vez hasta encontrar la proporci\u00f3n adecuada de agua y hojas. <\/p>&#13;\n<p><strong>Controla la temperatura del agua: <\/strong>Primero, usa agua hirviendo para asegurarte de que los brotes y las hojas de t\u00e9 secas se absorban completamente y se infusionen; en una segunda etapa de la preparaci\u00f3n, prefiere una temperatura del agua m\u00e1s baja: 90-95 \u00b0C durante los meses de invierno y 60-65 \u00b0C en verano.<\/p>&#13;\n<p><strong>Conoce tu t\u00e9: <\/strong>La primera infusi\u00f3n al estilo del abuelo probablemente no sea excelente, pero eso no significa que no se pueda lograr. \u00a1Sigue documentando tus pruebas y errores hasta que encuentres el punto perfecto al preparar tu t\u00e9 al estilo del abuelo! <\/p>&#13;\n","protected":false},"excerpt":{"rendered":"<p>&#13; Si alguna vez has visitado China o has vivido aqu\u00ed, habr\u00e1s notado que mucha gente, especialmente los residentes mayores, disfruta bebiendo el t\u00e9 en una taza o termo, dej\u00e1ndolo reposar todo el d\u00eda y, ocasionalmente, a\u00f1adi\u00e9ndole agua hirviendo. Taxistas, mec\u00e1nicos y peque\u00f1os comerciantes comparten esta pasi\u00f3n por lo que en Occidente se conoce como [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":823,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-947","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Preparando el t\u00e9 al &#039;estilo del abuelo&#039; - Sinellia Tea<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Preparando el t\u00e9 al &#039;estilo del abuelo&#039; - Sinellia Tea\" \/>\n<meta property=\"og:description\" content=\"&#013; Si alguna vez has visitado China o has vivido aqu\u00ed, habr\u00e1s notado que mucha gente, especialmente los residentes mayores, disfruta bebiendo el t\u00e9 en una taza o termo, dej\u00e1ndolo reposar todo el d\u00eda y, ocasionalmente, a\u00f1adi\u00e9ndole agua hirviendo. Taxistas, mec\u00e1nicos y peque\u00f1os comerciantes comparten esta pasi\u00f3n por lo que en Occidente se conoce como [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sinelliatea.com\/es\/preparando-el-te-al-estilo-del-abuelo\/\" \/>\n<meta property=\"og:site_name\" content=\"Sinellia Tea\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-02T02:48:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-22T16:20:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sinelliatea.com\/wp-content\/uploads\/2025\/08\/Flat_lay_of_various_tea_leaves_on_an_isolat_1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1152\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"st-admin-good\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"st-admin-good\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/sinelliatea.com\/es\/preparando-el-te-al-estilo-del-abuelo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/sinelliatea.com\/es\/preparando-el-te-al-estilo-del-abuelo\/\"},\"author\":{\"name\":\"st-admin-good\",\"@id\":\"https:\/\/sinelliatea.com\/#\/schema\/person\/080f78f1d0fa069e31567c3f20857beb\"},\"headline\":\"Preparando el t\u00e9 al &#8216;estilo del abuelo&#8217;\",\"datePublished\":\"2025-08-02T02:48:12+00:00\",\"dateModified\":\"2025-08-22T16:20:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/sinelliatea.com\/es\/preparando-el-te-al-estilo-del-abuelo\/\"},\"wordCount\":552,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/sinelliatea.com\/es\/preparando-el-te-al-estilo-del-abuelo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sinelliatea.com\/wp-content\/uploads\/2025\/08\/Flat_lay_of_various_tea_leaves_on_an_isolat_1.webp\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/sinelliatea.com\/es\/preparando-el-te-al-estilo-del-abuelo\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sinelliatea.com\/es\/preparando-el-te-al-estilo-del-abuelo\/\",\"url\":\"https:\/\/sinelliatea.com\/es\/preparando-el-te-al-estilo-del-abuelo\/\",\"name\":\"Preparando el t\u00e9 al 'estilo del abuelo' - Sinellia Tea\",\"isPartOf\":{\"@id\":\"https:\/\/sinelliatea.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sinelliatea.com\/es\/preparando-el-te-al-estilo-del-abuelo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sinelliatea.com\/es\/preparando-el-te-al-estilo-del-abuelo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sinelliatea.com\/wp-content\/uploads\/2025\/08\/Flat_lay_of_various_tea_leaves_on_an_isolat_1.webp\",\"datePublished\":\"2025-08-02T02:48:12+00:00\",\"dateModified\":\"2025-08-22T16:20:56+00:00\",\"author\":{\"@id\":\"https:\/\/sinelliatea.com\/#\/schema\/person\/080f78f1d0fa069e31567c3f20857beb\"},\"breadcrumb\":{\"@id\":\"https:\/\/sinelliatea.com\/es\/preparando-el-te-al-estilo-del-abuelo\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sinelliatea.com\/es\/preparando-el-te-al-estilo-del-abuelo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sinelliatea.com\/es\/preparando-el-te-al-estilo-del-abuelo\/#primaryimage\",\"url\":\"https:\/\/sinelliatea.com\/wp-content\/uploads\/2025\/08\/Flat_lay_of_various_tea_leaves_on_an_isolat_1.webp\",\"contentUrl\":\"https:\/\/sinelliatea.com\/wp-content\/uploads\/2025\/08\/Flat_lay_of_various_tea_leaves_on_an_isolat_1.webp\",\"width\":1152,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sinelliatea.com\/es\/preparando-el-te-al-estilo-del-abuelo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/sinelliatea.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Preparando el t\u00e9 al &#8216;estilo del abuelo&#8217;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sinelliatea.com\/#website\",\"url\":\"https:\/\/sinelliatea.com\/\",\"name\":\"Sinellia Tea\",\"description\":\"Desde las monta\u00f1as de China hasta tu taza, hojas seleccionadas con dedicaci\u00f3n y respeto por la tradici\u00f3n.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sinelliatea.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/sinelliatea.com\/#\/schema\/person\/080f78f1d0fa069e31567c3f20857beb\",\"name\":\"st-admin-good\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/sinelliatea.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/sinelliatea.com\/wp-content\/litespeed\/avatar\/3f74adf1fda693887d2a3547b8fd7f33.jpg?ver=1783717922\",\"contentUrl\":\"https:\/\/sinelliatea.com\/wp-content\/litespeed\/avatar\/3f74adf1fda693887d2a3547b8fd7f33.jpg?ver=1783717922\",\"caption\":\"st-admin-good\"},\"sameAs\":[\"https:\/\/sinelliatea.com\"],\"url\":\"https:\/\/sinelliatea.com\/es\/author\/st-admin-good\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Preparando el t\u00e9 al 'estilo del abuelo' - Sinellia Tea","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"Preparando el t\u00e9 al 'estilo del abuelo' - Sinellia Tea","og_description":"&#13; Si alguna vez has visitado China o has vivido aqu\u00ed, habr\u00e1s notado que mucha gente, especialmente los residentes mayores, disfruta bebiendo el t\u00e9 en una taza o termo, dej\u00e1ndolo reposar todo el d\u00eda y, ocasionalmente, a\u00f1adi\u00e9ndole agua hirviendo. Taxistas, mec\u00e1nicos y peque\u00f1os comerciantes comparten esta pasi\u00f3n por lo que en Occidente se conoce como [&hellip;]","og_url":"https:\/\/sinelliatea.com\/es\/preparando-el-te-al-estilo-del-abuelo\/","og_site_name":"Sinellia Tea","article_published_time":"2025-08-02T02:48:12+00:00","article_modified_time":"2025-08-22T16:20:56+00:00","og_image":[{"width":1152,"height":768,"url":"https:\/\/sinelliatea.com\/wp-content\/uploads\/2025\/08\/Flat_lay_of_various_tea_leaves_on_an_isolat_1.webp","type":"image\/webp"}],"author":"st-admin-good","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"st-admin-good","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sinelliatea.com\/es\/preparando-el-te-al-estilo-del-abuelo\/#article","isPartOf":{"@id":"https:\/\/sinelliatea.com\/es\/preparando-el-te-al-estilo-del-abuelo\/"},"author":{"name":"st-admin-good","@id":"https:\/\/sinelliatea.com\/#\/schema\/person\/080f78f1d0fa069e31567c3f20857beb"},"headline":"Preparando el t\u00e9 al &#8216;estilo del abuelo&#8217;","datePublished":"2025-08-02T02:48:12+00:00","dateModified":"2025-08-22T16:20:56+00:00","mainEntityOfPage":{"@id":"https:\/\/sinelliatea.com\/es\/preparando-el-te-al-estilo-del-abuelo\/"},"wordCount":552,"commentCount":0,"image":{"@id":"https:\/\/sinelliatea.com\/es\/preparando-el-te-al-estilo-del-abuelo\/#primaryimage"},"thumbnailUrl":"https:\/\/sinelliatea.com\/wp-content\/uploads\/2025\/08\/Flat_lay_of_various_tea_leaves_on_an_isolat_1.webp","inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sinelliatea.com\/es\/preparando-el-te-al-estilo-del-abuelo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sinelliatea.com\/es\/preparando-el-te-al-estilo-del-abuelo\/","url":"https:\/\/sinelliatea.com\/es\/preparando-el-te-al-estilo-del-abuelo\/","name":"Preparando el t\u00e9 al 'estilo del abuelo' - Sinellia Tea","isPartOf":{"@id":"https:\/\/sinelliatea.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sinelliatea.com\/es\/preparando-el-te-al-estilo-del-abuelo\/#primaryimage"},"image":{"@id":"https:\/\/sinelliatea.com\/es\/preparando-el-te-al-estilo-del-abuelo\/#primaryimage"},"thumbnailUrl":"https:\/\/sinelliatea.com\/wp-content\/uploads\/2025\/08\/Flat_lay_of_various_tea_leaves_on_an_isolat_1.webp","datePublished":"2025-08-02T02:48:12+00:00","dateModified":"2025-08-22T16:20:56+00:00","author":{"@id":"https:\/\/sinelliatea.com\/#\/schema\/person\/080f78f1d0fa069e31567c3f20857beb"},"breadcrumb":{"@id":"https:\/\/sinelliatea.com\/es\/preparando-el-te-al-estilo-del-abuelo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sinelliatea.com\/es\/preparando-el-te-al-estilo-del-abuelo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sinelliatea.com\/es\/preparando-el-te-al-estilo-del-abuelo\/#primaryimage","url":"https:\/\/sinelliatea.com\/wp-content\/uploads\/2025\/08\/Flat_lay_of_various_tea_leaves_on_an_isolat_1.webp","contentUrl":"https:\/\/sinelliatea.com\/wp-content\/uploads\/2025\/08\/Flat_lay_of_various_tea_leaves_on_an_isolat_1.webp","width":1152,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/sinelliatea.com\/es\/preparando-el-te-al-estilo-del-abuelo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sinelliatea.com\/es\/"},{"@type":"ListItem","position":2,"name":"Preparando el t\u00e9 al &#8216;estilo del abuelo&#8217;"}]},{"@type":"WebSite","@id":"https:\/\/sinelliatea.com\/#website","url":"https:\/\/sinelliatea.com\/","name":"Sinellia Tea","description":"Desde las monta\u00f1as de China hasta tu taza, hojas seleccionadas con dedicaci\u00f3n y respeto por la tradici\u00f3n.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sinelliatea.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/sinelliatea.com\/#\/schema\/person\/080f78f1d0fa069e31567c3f20857beb","name":"st-admin-good","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sinelliatea.com\/#\/schema\/person\/image\/","url":"https:\/\/sinelliatea.com\/wp-content\/litespeed\/avatar\/3f74adf1fda693887d2a3547b8fd7f33.jpg?ver=1783717922","contentUrl":"https:\/\/sinelliatea.com\/wp-content\/litespeed\/avatar\/3f74adf1fda693887d2a3547b8fd7f33.jpg?ver=1783717922","caption":"st-admin-good"},"sameAs":["https:\/\/sinelliatea.com"],"url":"https:\/\/sinelliatea.com\/es\/author\/st-admin-good\/"}]}},"_links":{"self":[{"href":"https:\/\/sinelliatea.com\/es\/wp-json\/wp\/v2\/posts\/947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sinelliatea.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sinelliatea.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sinelliatea.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sinelliatea.com\/es\/wp-json\/wp\/v2\/comments?post=947"}],"version-history":[{"count":0,"href":"https:\/\/sinelliatea.com\/es\/wp-json\/wp\/v2\/posts\/947\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sinelliatea.com\/es\/wp-json\/wp\/v2\/media\/823"}],"wp:attachment":[{"href":"https:\/\/sinelliatea.com\/es\/wp-json\/wp\/v2\/media?parent=947"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sinelliatea.com\/es\/wp-json\/wp\/v2\/categories?post=947"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sinelliatea.com\/es\/wp-json\/wp\/v2\/tags?post=947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}